{"id":4005,"date":"2024-03-14T10:37:37","date_gmt":"2024-03-14T10:37:37","guid":{"rendered":"https:\/\/rokuageopark.fi\/ajanjakso\/jokiuomat-ja-suistot\/"},"modified":"2025-06-18T10:43:30","modified_gmt":"2025-06-18T10:43:30","slug":"jokiuomat-ja-suistot","status":"publish","type":"ajanjakso","link":"https:\/\/rokuageopark.fi\/de\/ajanjakso\/jokiuomat-ja-suistot\/","title":{"rendered":"Flussl\u00e4ufe und -deltas"},"featured_media":3879,"template":"","alue":[217,220,222],"class_list":["post-4005","ajanjakso","type-ajanjakso","status-publish","has-post-thumbnail","hentry","alue-jokialueet-de","alue-muhos-de","alue-oulujokilaakson-alue-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Flussl\u00e4ufe und -deltas - Rokua Geopark<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Flussl\u00e4ufe und -deltas - Rokua Geopark\" \/>\n<meta property=\"og:description\" content=\"[...]Weiterlesen\u00a0\u2026 from Flussl\u00e4ufe und -deltas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rokuageopark.fi\/de\/ajanjakso\/jokiuomat-ja-suistot\/\" \/>\n<meta property=\"og:site_name\" content=\"Rokua Geopark\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-18T10:43:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rokuageopark.fi\/wp-content\/uploads\/2024\/03\/Muhosjoki1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rokuageopark.fi\\\/de\\\/ajanjakso\\\/jokiuomat-ja-suistot\\\/\",\"url\":\"https:\\\/\\\/rokuageopark.fi\\\/de\\\/ajanjakso\\\/jokiuomat-ja-suistot\\\/\",\"name\":\"Flussl\u00e4ufe und -deltas - Rokua Geopark\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rokuageopark.fi\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rokuageopark.fi\\\/de\\\/ajanjakso\\\/jokiuomat-ja-suistot\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rokuageopark.fi\\\/de\\\/ajanjakso\\\/jokiuomat-ja-suistot\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rokuageopark.fi\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Muhosjoki1-scaled.jpg\",\"datePublished\":\"2024-03-14T10:37:37+00:00\",\"dateModified\":\"2025-06-18T10:43:30+00:00\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rokuageopark.fi\\\/de\\\/ajanjakso\\\/jokiuomat-ja-suistot\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/rokuageopark.fi\\\/de\\\/ajanjakso\\\/jokiuomat-ja-suistot\\\/#primaryimage\",\"url\":\"https:\\\/\\\/rokuageopark.fi\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Muhosjoki1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/rokuageopark.fi\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Muhosjoki1-scaled.jpg\",\"width\":2560,\"height\":1920,\"caption\":\"Ilmakuva Muhosjoesta\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rokuageopark.fi\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/rokuageopark.fi\\\/de\\\/\",\"name\":\"Rokua Geopark\",\"description\":\"Tervetuloa l\u00f6yt\u00f6retkelle\\u2028j\u00e4\u00e4kauden j\u00e4ljille\",\"publisher\":{\"@id\":\"https:\\\/\\\/rokuageopark.fi\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rokuageopark.fi\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rokuageopark.fi\\\/de\\\/#organization\",\"name\":\"Rokua Geopark\",\"url\":\"https:\\\/\\\/rokuageopark.fi\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/rokuageopark.fi\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/rokuageopark.fi\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/rokua_geopark-logo.png\",\"contentUrl\":\"https:\\\/\\\/rokuageopark.fi\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/rokua_geopark-logo.png\",\"width\":697,\"height\":697,\"caption\":\"Rokua Geopark\"},\"image\":{\"@id\":\"https:\\\/\\\/rokuageopark.fi\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Flussl\u00e4ufe und -deltas - Rokua Geopark","robots":{"index":"noindex","follow":"follow"},"og_locale":"de_DE","og_type":"article","og_title":"Flussl\u00e4ufe und -deltas - Rokua Geopark","og_description":"[...]Weiterlesen\u00a0\u2026 from Flussl\u00e4ufe und -deltas","og_url":"https:\/\/rokuageopark.fi\/de\/ajanjakso\/jokiuomat-ja-suistot\/","og_site_name":"Rokua Geopark","article_modified_time":"2025-06-18T10:43:30+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/rokuageopark.fi\/wp-content\/uploads\/2024\/03\/Muhosjoki1-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/rokuageopark.fi\/de\/ajanjakso\/jokiuomat-ja-suistot\/","url":"https:\/\/rokuageopark.fi\/de\/ajanjakso\/jokiuomat-ja-suistot\/","name":"Flussl\u00e4ufe und -deltas - Rokua Geopark","isPartOf":{"@id":"https:\/\/rokuageopark.fi\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rokuageopark.fi\/de\/ajanjakso\/jokiuomat-ja-suistot\/#primaryimage"},"image":{"@id":"https:\/\/rokuageopark.fi\/de\/ajanjakso\/jokiuomat-ja-suistot\/#primaryimage"},"thumbnailUrl":"https:\/\/rokuageopark.fi\/wp-content\/uploads\/2024\/03\/Muhosjoki1-scaled.jpg","datePublished":"2024-03-14T10:37:37+00:00","dateModified":"2025-06-18T10:43:30+00:00","inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rokuageopark.fi\/de\/ajanjakso\/jokiuomat-ja-suistot\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rokuageopark.fi\/de\/ajanjakso\/jokiuomat-ja-suistot\/#primaryimage","url":"https:\/\/rokuageopark.fi\/wp-content\/uploads\/2024\/03\/Muhosjoki1-scaled.jpg","contentUrl":"https:\/\/rokuageopark.fi\/wp-content\/uploads\/2024\/03\/Muhosjoki1-scaled.jpg","width":2560,"height":1920,"caption":"Ilmakuva Muhosjoesta"},{"@type":"WebSite","@id":"https:\/\/rokuageopark.fi\/de\/#website","url":"https:\/\/rokuageopark.fi\/de\/","name":"Rokua Geopark","description":"Tervetuloa l\u00f6yt\u00f6retkelle\u2028j\u00e4\u00e4kauden j\u00e4ljille","publisher":{"@id":"https:\/\/rokuageopark.fi\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rokuageopark.fi\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/rokuageopark.fi\/de\/#organization","name":"Rokua Geopark","url":"https:\/\/rokuageopark.fi\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rokuageopark.fi\/de\/#\/schema\/logo\/image\/","url":"https:\/\/rokuageopark.fi\/wp-content\/uploads\/2024\/04\/rokua_geopark-logo.png","contentUrl":"https:\/\/rokuageopark.fi\/wp-content\/uploads\/2024\/04\/rokua_geopark-logo.png","width":697,"height":697,"caption":"Rokua Geopark"},"image":{"@id":"https:\/\/rokuageopark.fi\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/rokuageopark.fi\/de\/wp-json\/wp\/v2\/ajanjakso\/4005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rokuageopark.fi\/de\/wp-json\/wp\/v2\/ajanjakso"}],"about":[{"href":"https:\/\/rokuageopark.fi\/de\/wp-json\/wp\/v2\/types\/ajanjakso"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rokuageopark.fi\/de\/wp-json\/wp\/v2\/media\/3879"}],"wp:attachment":[{"href":"https:\/\/rokuageopark.fi\/de\/wp-json\/wp\/v2\/media?parent=4005"}],"wp:term":[{"taxonomy":"alue","embeddable":true,"href":"https:\/\/rokuageopark.fi\/de\/wp-json\/wp\/v2\/alue?post=4005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}